{"id":2215,"count":1,"description":"","link":"https:\/\/www.apnikheti.com\/progressivefarmers\/tag\/%e0%a8%95%e0%a9%b1%e0%a8%9a%e0%a9%80-%e0%a8%b9%e0%a8%b2%e0%a8%a6%e0%a9%80-%e0%a8%a6%e0%a8%be-%e0%a8%86%e0%a8%9a%e0%a8%be%e0%a8%b0\/?lang=pa","name":"\u0a15\u0a71\u0a1a\u0a40 \u0a39\u0a32\u0a26\u0a40 \u0a26\u0a3e \u0a06\u0a1a\u0a3e\u0a30","slug":"%e0%a8%95%e0%a9%b1%e0%a8%9a%e0%a9%80-%e0%a8%b9%e0%a8%b2%e0%a8%a6%e0%a9%80-%e0%a8%a6%e0%a8%be-%e0%a8%86%e0%a8%9a%e0%a8%be%e0%a8%b0","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0a15\u0a71\u0a1a\u0a40 \u0a39\u0a32\u0a26\u0a40 \u0a26\u0a3e \u0a06\u0a1a\u0a3e\u0a30 Archives - Progressive Farmers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.apnikheti.com\/progressivefarmers\/tag\/\u0a15\u0a71\u0a1a\u0a40-\u0a39\u0a32\u0a26\u0a40-\u0a26\u0a3e-\u0a06\u0a1a\u0a3e\u0a30\/?lang=pa\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0a15\u0a71\u0a1a\u0a40 \u0a39\u0a32\u0a26\u0a40 \u0a26\u0a3e \u0a06\u0a1a\u0a3e\u0a30 Archives - Progressive Farmers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.apnikheti.com\/progressivefarmers\/tag\/\u0a15\u0a71\u0a1a\u0a40-\u0a39\u0a32\u0a26\u0a40-\u0a26\u0a3e-\u0a06\u0a1a\u0a3e\u0a30\/?lang=pa\" \/>\n<meta property=\"og:site_name\" content=\"Progressive Farmers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.apnikheti.com\/progressivefarmers\/tag\/%e0%a8%95%e0%a9%b1%e0%a8%9a%e0%a9%80-%e0%a8%b9%e0%a8%b2%e0%a8%a6%e0%a9%80-%e0%a8%a6%e0%a8%be-%e0%a8%86%e0%a8%9a%e0%a8%be%e0%a8%b0\/?lang=pa\",\"url\":\"https:\/\/www.apnikheti.com\/progressivefarmers\/tag\/%e0%a8%95%e0%a9%b1%e0%a8%9a%e0%a9%80-%e0%a8%b9%e0%a8%b2%e0%a8%a6%e0%a9%80-%e0%a8%a6%e0%a8%be-%e0%a8%86%e0%a8%9a%e0%a8%be%e0%a8%b0\/?lang=pa\",\"name\":\"\u0a15\u0a71\u0a1a\u0a40 \u0a39\u0a32\u0a26\u0a40 \u0a26\u0a3e \u0a06\u0a1a\u0a3e\u0a30 Archives - Progressive Farmers\",\"isPartOf\":{\"@id\":\"http:\/\/www.apnikheti.com\/progressivefarmers\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.apnikheti.com\/progressivefarmers\/tag\/%e0%a8%95%e0%a9%b1%e0%a8%9a%e0%a9%80-%e0%a8%b9%e0%a8%b2%e0%a8%a6%e0%a9%80-%e0%a8%a6%e0%a8%be-%e0%a8%86%e0%a8%9a%e0%a8%be%e0%a8%b0\/?lang=pa#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.apnikheti.com\/progressivefarmers\/tag\/%e0%a8%95%e0%a9%b1%e0%a8%9a%e0%a9%80-%e0%a8%b9%e0%a8%b2%e0%a8%a6%e0%a9%80-%e0%a8%a6%e0%a8%be-%e0%a8%86%e0%a8%9a%e0%a8%be%e0%a8%b0\/?lang=pa#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.apnikheti.com\/progressivefarmers\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0a15\u0a71\u0a1a\u0a40 \u0a39\u0a32\u0a26\u0a40 \u0a26\u0a3e \u0a06\u0a1a\u0a3e\u0a30\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.apnikheti.com\/progressivefarmers\/#website\",\"url\":\"http:\/\/www.apnikheti.com\/progressivefarmers\/\",\"name\":\"Progressive Farmers\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.apnikheti.com\/progressivefarmers\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0a15\u0a71\u0a1a\u0a40 \u0a39\u0a32\u0a26\u0a40 \u0a26\u0a3e \u0a06\u0a1a\u0a3e\u0a30 Archives - Progressive Farmers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.apnikheti.com\/progressivefarmers\/tag\/\u0a15\u0a71\u0a1a\u0a40-\u0a39\u0a32\u0a26\u0a40-\u0a26\u0a3e-\u0a06\u0a1a\u0a3e\u0a30\/?lang=pa","og_locale":"en_US","og_type":"article","og_title":"\u0a15\u0a71\u0a1a\u0a40 \u0a39\u0a32\u0a26\u0a40 \u0a26\u0a3e \u0a06\u0a1a\u0a3e\u0a30 Archives - Progressive Farmers","og_url":"https:\/\/www.apnikheti.com\/progressivefarmers\/tag\/\u0a15\u0a71\u0a1a\u0a40-\u0a39\u0a32\u0a26\u0a40-\u0a26\u0a3e-\u0a06\u0a1a\u0a3e\u0a30\/?lang=pa","og_site_name":"Progressive Farmers","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.apnikheti.com\/progressivefarmers\/tag\/%e0%a8%95%e0%a9%b1%e0%a8%9a%e0%a9%80-%e0%a8%b9%e0%a8%b2%e0%a8%a6%e0%a9%80-%e0%a8%a6%e0%a8%be-%e0%a8%86%e0%a8%9a%e0%a8%be%e0%a8%b0\/?lang=pa","url":"https:\/\/www.apnikheti.com\/progressivefarmers\/tag\/%e0%a8%95%e0%a9%b1%e0%a8%9a%e0%a9%80-%e0%a8%b9%e0%a8%b2%e0%a8%a6%e0%a9%80-%e0%a8%a6%e0%a8%be-%e0%a8%86%e0%a8%9a%e0%a8%be%e0%a8%b0\/?lang=pa","name":"\u0a15\u0a71\u0a1a\u0a40 \u0a39\u0a32\u0a26\u0a40 \u0a26\u0a3e \u0a06\u0a1a\u0a3e\u0a30 Archives - Progressive Farmers","isPartOf":{"@id":"http:\/\/www.apnikheti.com\/progressivefarmers\/#website"},"breadcrumb":{"@id":"https:\/\/www.apnikheti.com\/progressivefarmers\/tag\/%e0%a8%95%e0%a9%b1%e0%a8%9a%e0%a9%80-%e0%a8%b9%e0%a8%b2%e0%a8%a6%e0%a9%80-%e0%a8%a6%e0%a8%be-%e0%a8%86%e0%a8%9a%e0%a8%be%e0%a8%b0\/?lang=pa#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.apnikheti.com\/progressivefarmers\/tag\/%e0%a8%95%e0%a9%b1%e0%a8%9a%e0%a9%80-%e0%a8%b9%e0%a8%b2%e0%a8%a6%e0%a9%80-%e0%a8%a6%e0%a8%be-%e0%a8%86%e0%a8%9a%e0%a8%be%e0%a8%b0\/?lang=pa#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.apnikheti.com\/progressivefarmers\/"},{"@type":"ListItem","position":2,"name":"\u0a15\u0a71\u0a1a\u0a40 \u0a39\u0a32\u0a26\u0a40 \u0a26\u0a3e \u0a06\u0a1a\u0a3e\u0a30"}]},{"@type":"WebSite","@id":"http:\/\/www.apnikheti.com\/progressivefarmers\/#website","url":"http:\/\/www.apnikheti.com\/progressivefarmers\/","name":"Progressive Farmers","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.apnikheti.com\/progressivefarmers\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.apnikheti.com\/progressivefarmers\/wp-json\/wp\/v2\/tags\/2215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apnikheti.com\/progressivefarmers\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.apnikheti.com\/progressivefarmers\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.apnikheti.com\/progressivefarmers\/wp-json\/wp\/v2\/posts?tags=2215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}